{"id":171,"date":"2024-10-17T11:42:10","date_gmt":"2024-10-17T09:42:10","guid":{"rendered":"https:\/\/bazar-komoda.cz\/?page_id=171"},"modified":"2025-12-31T09:32:31","modified_gmt":"2025-12-31T08:32:31","slug":"kontaktni-informace","status":"publish","type":"page","link":"https:\/\/dekohra.eu\/de\/kontaktni-informace\/","title":{"rendered":"Kontaktinformationen"},"content":{"rendered":"<h3 class=\"wp-block-heading has-text-align-center\">Kontaktinformationen<\/h3>\n\n\n\n<p class=\"has-text-align-center\"><strong>Kontakt<\/strong><strong>&nbsp;unser,<\/strong><strong>&nbsp;R<\/strong><strong>adi&nbsp;<\/strong><strong>Zu dir<\/strong><strong>&nbsp;Wir beraten Sie bei der Auswahl.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><img decoding=\"async\" style=\"width: 200px;\" src=\"https:\/\/dekohra.eu\/_obchody\/go4874\/prilohy\/2\/kontaktni-informace-logo.jpg.big.jpg\" alt=\"\">E-Mail:\u00a0 \u00a0 \u00a0<a href=\"mailto:info@dekohra.eu\">info@dekohla.eu<\/a><\/h3>\n\n\n\n<h4 class=\"wp-block-heading alignwide has-text-align-center\">Telefon: +420 704 043 886<\/h4>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\" style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\"\/>\n\n\n\n<div style=\"height:36px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:18% auto\"><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/dekohra.eu\/wp-content\/uploads\/2024\/10\/osobni-dotek-kazdeho-bytu-unikatni-jmenovky-na-dve.jpg\" alt=\"\" class=\"wp-image-12309 size-full\" srcset=\"https:\/\/dekohra.eu\/wp-content\/uploads\/2024\/10\/osobni-dotek-kazdeho-bytu-unikatni-jmenovky-na-dve.jpg 300w, https:\/\/dekohra.eu\/wp-content\/uploads\/2024\/10\/osobni-dotek-kazdeho-bytu-unikatni-jmenovky-na-dve-16x12.jpg 16w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Martina \u0160edrlova<\/strong> <\/p>\n\n\n\n<p>Betreiber- und E-Commerce-Verwaltung<\/p>\n\n\n\n<p>ID: 19484194<\/p>\n\n\n\n<p><a href=\"mailto:poptavky@dekohra.eu\">anfragen@dekohla.eu<\/a><\/p>\n\n\n\n<p>&nbsp;<a href=\"mailto:info@dekohra.eu\">info@dekohla.eu<\/a><\/p>\n\n\n\n<p>+420 704 043 886<\/p>\n\n\n\n<p>Rybnicni 550\/15, Miroslav<\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\" style=\"margin-top:var(--wp--preset--spacing--20);margin-bottom:var(--wp--preset--spacing--20)\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"toc-telefon-420-216-216-516\"><\/h3>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pers\u00f6nliche Abholung der Ware<\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"toc-telefon-420-216-216-516\">&nbsp;Nach Vereinbarung +420 704 043 886<\/h4>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Unsere Bankverbindung<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Flasche:&nbsp;<strong>KB<\/strong><\/li>\n\n\n\n<li>Kontonummer:&nbsp;<strong>108533001\/0100<\/strong><\/li>\n\n\n\n<li>IBAN:&nbsp;<strong>CZ2601000000000108533001<\/strong><\/li>\n\n\n\n<li>PEITSCHE:&nbsp;<strong>COMBCZPP<\/strong><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/dekohra.eu\/class\/tiny_mce\/themes\/advanced\/img\/trans.gif\" alt=\"\"\/><\/figure>\n\n\n\n<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d463.2571559991711!2d16.31947062152026!3d48.94247504727607!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x4712b177f84e09c7%3A0x48c730588dde7c1e!2sDekohra.eu!5e0!3m2!1scs!2scz!4v1729883501043!5m2!1scs!2scz\" width=\"500\" height=\"400\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Anfrageformular<\/h4>\n\n\n<div class=\"wp-block-jetpack-contact-form\"><a href=\"https:\/\/dekohra.eu\/de\/kontaktni-informace\/\" target=\"_blank\" rel=\"noopener noreferrer\">Formular einreichen.<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Kontaktn\u00ed informace Kontaktujte&nbsp;n\u00e1s,&nbsp;r\u00e1di&nbsp;V\u00e1m&nbsp;porad\u00edme s v\u00fdb\u011brem. Email:\u00a0 \u00a0 \u00a0info@dekohra.eu Telefon:&nbsp; &nbsp; &nbsp; +420 704 043 886 Martina \u0160edrlov\u00e1 Provozovatel a Spr\u00e1va [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-171","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"dekohra.eu","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"Das angezeigte Beitragsbild sollte mindestens 200x200 px gro\u00df sein, damit Facebook und andere Social-Media-Websites es \u00fcbernehmen.","pluginReviewed":true,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"kontaktni-informace","permalinkFormat":"https:\/\/dekohra.eu\/de\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/dekohra.eu\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":false,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"Benutzername","primaryTerm":0,"authorName":"Martina \u0160edrlov\u00e1","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["abgelenkt","abgesturzt","absolut","abstossend","aburd","abweisen","adaquat","aggressiv","ahnungslos","akkurat","alarmierend","alarmiert","albtraum","all-inclusive","allererste","allererster","allererstes","alleswisser","am schlechtesten","am wichtigsten","angewidert","angriff","angsteinflossend","angstlich","animiert","ankundigung","anonym","anpassbar","anspruchslos","anstossig","antagonistisch","apokalypse","applaus","argumentativ","arm","armageddon","arrogant","atemberaubend","attacke","attraktiv","aufdeckend","aufgebracht","aufgedeckt","aufgeregt","aufheiternd","aufregend","aufregende","aufregenden","aufregung","aufstachelnd","aufstandisch","aufsteigend","auftreibend","augenoffnend","ausgelassen","ausgeruht","ausgespielt","ausgewahlt","ausgewuhlt","ausnutzen","aussergewohnlich","autark","authentisch","autoritat","backdoor","badass","beangstigend","bedenklich","bedingungslos","bedrohen","bedroht","beforderung","befreit","befriedigend","befriedigt","begehren","begeistern","begeistert","begeisterung","beherzt","behind the scenes","beichte","beleidigung","belohnung","bemerkenswert","beneiden","bequem","beruhmt","beschadigen","beschamend","beschmutzt","beschuldigen","beschutzen","besitz","bessesen","bestatigen","bestatigt","beste","bestimmt","bestrafen","betrug","betrugen","bewahrt","bewiesen","bewiesenermassen","bewusst","bezahlbar","bezaubernd","bizarre","bleich","blendend","blut","blutbad","blutig","bombe","bonanza","bonus","bosartig","bose","boshaft","brilliant","brodelnd","brutal","budget","bullshit","bully","bunt","bunte","bunten","case study","cash","challenge","challgene","chaos","cheat-sheet","clever","content","cool","courage","dankbar","daruber redet keiner","deadline","definitiv","dekadent","demoralisierend","demut","desillusioniert","detailiert","diagnose","die wahrheit","direkt","disastros","discount","dokument","dollar","dominieren","doppelt","download","dreckig","dreifach","dreistigkeit","dringend","dringlichkeit","dumm","dummkopf","dummlich","durchbruch","duselig","dynamik","echt","effektiv","effizient","ehrlich","eier","eifersuchtig","eifrig","eindeutig","eindrucksvoll","eine stufe besser","einfach","einfachheit","einfallsreich","eingebildet","eingeschrankt","eingesperrt","einmalig","einsam","eintauchen","einzigartig","eisern","eliminieren","elite","empathie","empfehle","empfehlen","endeffekt","energie","energisch","enorm","entdecken","entfesselt","entfremdet","enthullen","enthullung","enthusiastisch","entmachtet","entsetzlich","entspannt","entzuckend","entzunden","epidemisch","episch","erbarmlich","erfolg","erfolgreich","erfolgsbilanz","erfreut","erfullen","erfullt","ergebnisse","ergreifen","erhaben","erheben","erhohen","erledigt","ermachtigt","ermudet","ernmutigt","ernsthaft","erobern","erroten","errungenschaft","erschaffen","erschrocken","ersehnen","ersparnisse","erstattbar","erstatten","erstaunlich","erste","ertrinken","essentiell","ethisch","euphorisch","exakt","exklusiv","exklusivitat","exkuisit","experte","explodieren","explosiv","exposed","extrem","exzellent","fahig","fahigkeiten","fail","falle","fantasie","fantastischen","farbenfroh","farbenfrohe","faszinierend","faszinierende","faul","faux pas","faux","fehler","feindselig","feldstudie","fesselnd","festlich","festmahl","festplatte","final","flirt","fluchtling","flussig","fokus","fokussiert","folter","formel","frech","freebie","frei","freiheit","freudig","friedlich","frohlich","frohlichkeit","frustriert","fundamental","fur immer","furchtbar","furchtlos","gangster","garantiert","geblendet","geehrt","gefahr","gefahrlich","gefangen","gefangnis","gefeuert","gegensatzlich","gehassig","geheimnis","geheimnisse","geil","geisseln","geist","geistesgestort","gelassen","geld zuruck","geld","genial","gepackt","gerade angekommen","gerissen","geschenk","geschmuggelt","geschutzt","gestandnis","gestandnisse","gestopft","gestresst","gesucht","gesund","getauscht","getestet","getotet","gewaltig","gewalttatig","gewidmet","gewinnspiel","gier","gierig","gift","giftig","gigantisch","giveaway","glamourose","glanzend","glaube","glaubwurdig","gleichmassig","glittering","glitzernde","gluckselig","golden","grandios","grandiose","grandiosen","grandioses","grauenhaft","grausamkeit","grinsen","groesste","gross","grossartig","grossartig","grossartige","grossartigen","grossartiger","grossartiges","grosse","grossen","grosste","grosszugig","grotesk","grube","grundlegend","gruselig","gunstig","hack","hamisch","hammer","handelsgeheimnis","hartnackig","hass","heilig","heimlich","heisshunger","heisshungrig","heiter","held","hell","herablassend","herausfordernd","herausforderung","herausvorderung","herrlichen","herrschend","hervorragend","herz","herzbrechend","herzerwahrmend","heute","hightech","hilflosigkeit","hilfreich","hilfsbereit","himmlisch","hinterhaltig","hoax","hocheffektiv","hochnasig","hochste","hoffnung","hoffnungsvoll","holle","holocaust","horror","how to","humor","hungrige","hurrikan","hypnotisch","hypnotisierend","idiot","idiotisch","illegal","immer","informativ","inhalt","inkompetent","innovativ","insider","inspirierend","inspiriert","intelligent","intensiv","interessant","interessante","invasion","investment","ist da","jackpot","jederzeit kundigen","jetzt","jubilant","jumpstart","jung","kadaver","kampf","katapult","katastrophe","kaufen","kein risiko","keine verpflichtung","kickstart","kindisch","kitschig","klaglich","klar","knast","kollabieren","kollosal","komfortabel","komisch","kompetitiv","komplett","kompromiss","komsich","konstruktiv","kontrollierend","kontrollverlust","kooperativ","kopie","korrupt","kostenlos","kraftlos","kraftvoll","krankhaft","kreativ","kreative","kriese","kritisch","kruppel","lachen","lacherlich","lahm","last minute","lauernd","lebendig","lebenslanglich","lecken","lecker","legendar","legitim","leiche","leicht","leiden","leider","leise","letzte chance","letzte","leuchtend","liberal","licht","liebe","liebenswurdig","liebevoll","life-changing","limitiert","lohnend","loser","losung","lugen","lugend","lukrativ","lust","lustig","lustige","lustigsten","luxorios","magisch","mainstream","mammut","manipulativ","massiv","masterclass","meditierend","meiseter","meistverkauft","meltdown","millionen","mind-blowing","minderwertig","minimalist","missbrauch","misstrauisch","mittelmassig","mittig","modern","moderne","moglichkeiten","monetarisieren","monumental","mord","motiviert","muhelos","muhevoll","mull","mut","mutig","nachmachen","nachteile","nackt","nagel","naiv","natural","nazi","neid","nervos","neu","niedertrachtig","niemals","notfall","notiert","nutzlich","nutzlos","offensichtlich","offiziel","offnen","ohne hintergedanken","ok","okay","okonomisch","on-demand","opfer","optimistisch","overnight","packend","panik","panzer","paralisiert","pas","passioniert","pause","payback","peinlich","perfekt","perplex","perskeptive","pessimistisch","pfund","piranha","pleite","plotzlich","pochend","polarisierend","popular","portfolio","praktisch","preis","prestige","privat","privatsphare","priviligiert","problem","produktiv","professionell","profit","profitabel","provokativ","provozierend","prozess","psychologisch","qual","qualen","qualitat","rabatt","rache","rachsuchtig","raffiniert","rasend","rat","rau","recherche","reduziert","reflektieren","regeln","reich","reiche","reichtum","relaxed","report","responsive","revolutionar","riesig","risiko","riskant","riskieren","rotzfrech","rowdy","ruckrat","ruckschlag","rucksichtlos","ruhig","ruiniert","sabotiert","sadistisch","sale","sarkastisch","scam","schabig","schadigend","schadlich","schamlos","schatz","schicksal","schlachten","schlafen","schlag","schlau","schlimm","schmerzhaft","schmerzlos","schmuggel","schnell","schnellstart","schokierend","schonheit","schrecklich","schreien","schritt fur schritt","schuld","schuldlos","schwach","schwarm","schwarzmarkt","schwerkraft","schwinden","sechsstellig","sehenswerte","selbsthass","selten","sensationell","sex","sexy","sicher","sicherheit","sicherlich","sieg","sill","simpel","sinnlich","sinnlos","skandal","skandalos","skill","sklave","sneak-peek","snob","sofort gespart","sofort","sollte","sonnig","sonnige","sonnigen","sorgen","sorgfaltig","sorglos","spannend","sparen","sparsam","spass","spassig","spektakular","speziell","spielen","spoiler","spontan","spotlight","stabil","stark","start","stoisch","stolz","stop","strahlend","strangulieren","strategie","studien","stumperhaft","stur","sunden","sundigend","super","superb","survival","tapfer","tauschend","teaser","technologie","terror","terrorist","teuer","tief","tiefgreifend","tierisch","tod","todlich","toll","tolle","toller","tortur","tot","tote","toten","totend","toxisch","tragisch","tragodie","transfomieren","transparenz","trauma","traumatisiert","traurigkeit","trend","tricks","trigger","triumpf","trocken","trotz","trugerisch","tweaks","tyrann","ubel","uberfordert","uberkommen","uberleben","uberlegen","uberraschend","uberrascht","uberraschung","uberwaltigend","uberwinden","ultimativ","umfassend","umstritten","umwerfend","unatorisiert","unaufhaltbar","unausgelasted","unbedacht","unbeliebt","unbeschwert","unbewusst","undercover","undokumentiert","unehrlich","unentschlossen","unerwartet","unfahig","ungeduldig","ungedult","ungehort","ungemutlich","ungerechtfertigt","ungesehen","ungetrubt","ungewohnlich","ungezogen","unglaublich","unglaubliches","uninteressiert","unkontrollierbar","unkonventionell","unlimitiert","unpenetrierbar","unschuldig","unsicher","unstabil","unter verschluss","untergrund","unterhaltsam","unterstutz","unterstutzend","unubertroffen","unvergesslich","unverneinbar","unvoreingenommen","unwiderstehlich","unwirtlich","unzensiert","unzuverlassig","up-selling","vaporisieren","verangstigt","verantwortlich","verargert","verarscht","verbessert","verbluffend","verblufft","verboten","verbreiten","verdachtig","verdammt","verdeckt","vereinfacht","verfuhrend","vergebend","vergessen","vergleich","verhauen","verifizieren","verkommen","verlegen","verletzbar","verletzt","verlockend","verloren","vermasselt","vermeiden","vermogen","vernichten","vernichtend","vernunftig","veroffentlichung","verpassen","verraterisch","verruckt","versagen","verschwitzt","versichert","verspielt","versprechend","versteckt","vertrauenswurdig","vertraulich","vertraumt","verurteilend","verwunderlich","verwundet","verzaubernd","verzweifelt","vierfach","vogelfrei","vollig","vollstandig","vorsicht","vorstellungskraft","vorteil","wachstum","wagemutig","wahnsinn","wahnsinnig","wahrhaftig","wahrheit","wahrheitsgemass","wahrscheinlich","warnung","was dir keiner sagt","wehleidig","welt","wenig bekannt","wert","wertvoll","wichtig","widerlich","wiedererkannt","wild","wilde","wilden","willensstarke","wirr","wohltatigkeit","wortlich","wunder","wunderbar","wunderbaren","wunderschon","wutend","zeichen","zeitig","zen","zensiert","zerschlagen","zerschmetternd","zerstorend","zertifiziert","zielorientiert","zischend","zischt","zocken","zogernd","zugeben","zuruckgehalten","zuruckgelassen","zuruckweisen","zusatzlich","zutaten","zuverlassig","zwangsernahrt","zweifelnd","zwickend","zwingend","einfache","einfachen","einfaches","einfacher","simple","simplen","simples","simpler","besten","bestes","bester","beste","bestbewertet","bestbewerteten","bestbewertete","bestbewerteter","bestbewertetes","\u00fcberraschende","\u00fcberraschenden","\u00fcberraschendes","\u00fcberraschender","hilfreiche","hilfreiches","hilfreichen","hilfreicher","f\u00f6rdern","unterst\u00fctzen","helfen","spielerisch","spannende","spannendes","spannenden","spannender","gro\u00dfartige","gro\u00dfartiges","gro\u00dfartigen","gro\u00dfartiger","ideal","ideales","idealen","idealer","faszinierend","faszinierendes","faszinierenden","faszinierender","wichtig","wichtige","wichtiges","wichtigen","wichtiger","sicher","sichere","sicheres","sicheren","sicherer","umfassende","umfassendes","umfassenden","umfassender","ultimative","ultimatives","ultimativen","ultimativer","einzigartige","einzigartiges","einzigartigen","einzigartiger"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2\\u00C4]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OE":"[\\u00D6]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","UE":"[\\u00DC]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3\\u00E4]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oe":"[\\u00f6]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","ue":"[\\u00FC]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":true},"homeUrl":"https:\/\/dekohra.eu\/de","objectID":171,"objectType":"post","locale":"de","localeFull":"de_DE","overlayImages":{"play":{"name":"Wiedergabezeichen","url":"https:\/\/dekohra.eu\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/storage\/2a113300\/f117734a-403d-4bf7-bed0-7d96077e8ed0\/dekohra.eu\/app_1749569695\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF-Symbol","url":"https:\/\/dekohra.eu\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/storage\/2a113300\/f117734a-403d-4bf7-bed0-7d96077e8ed0\/dekohra.eu\/app_1749569695\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/dekohra.eu\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fdekohra.eu%2Fde&r=https%3A%2F%2Fdekohra.eu%2Fde%2Fwp-json%2Fwp%2Fv2%2Fpages%2F171%3Fnonce%3Dbb7b1c833b&pro=1","maxTags":100,"trendsIcon":"<svg width=\"100%\" height=\"100%\" viewBox=\"0 0 36 36\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" fit=\"\" preserveAspectRatio=\"xMidYMid meet\" focusable=\"false\">\n\t\t<g id=\"Page-1\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t<g id=\"Trends-Arrow\">\n\t\t\t\t<g id=\"TrendsArrow\">\n\t\t\t\t\t<path d=\"M1.11227159,26.3181534 L10.2875029,17.1429221 L13.7152617,20.5706809 L4.5400304,29.7459122 C4.20518633,30.0807563 3.66229681,30.0807562 3.32745277,29.7459122 L1.11136262,27.529822 C0.776518575,27.194978 0.776518548,26.6520885 1.11136262,26.3172444 L1.11227159,26.3181534 Z\" id=\"Shape\" fill=\"#4285F4\" fill-rule=\"nonzero\"><\/path>\n\t\t\t\t\t<path d=\"M14.3201543,14.3211528 L22.283717,22.2847155 L19.4658829,25.1025495 C19.1310388,25.4373936 18.5881494,25.4373937 18.2533053,25.1025495 L10.2906516,17.1398959 L13.1084857,14.3220618 C13.4429747,13.987572 13.9851638,13.9871653 14.3201543,14.3211528 Z\" id=\"Shape\" fill=\"#EA4335\" fill-rule=\"nonzero\"><\/path>\n\t\t\t\t\t<polygon id=\"Rectangle-path\" fill=\"#FABB05\" fill-rule=\"nonzero\" points=\"18.8573051 18.8577571 28.2843236 9.43073862 31.7120824 12.8584974 22.2850639 22.2855159\"><\/polygon>\n\t\t\t\t\t<path d=\"M35.0711567,15.5054713 L35.0711567,7 L35.0711567,7 C35.0711567,6.44771525 34.6234415,6 34.0711567,6 L25.5656854,6 L25.5656854,6 C25.0134007,6 24.5656854,6.44771525 24.5656854,7 C24.5656854,7.26521649 24.6710423,7.5195704 24.8585786,7.70710678 L33.3640499,16.2125781 L33.3640499,16.2125781 C33.7545742,16.6031024 34.3877392,16.6031024 34.7782635,16.2125781 C34.9657999,16.0250417 35.0711567,15.7706878 35.0711567,15.5054713 Z\" id=\"Shape\" fill=\"#34A853\" fill-rule=\"nonzero\"><\/path>\n\t\t\t\t\t<rect id=\"Rectangle-path\" x=\"0\" y=\"0\" width=\"36\" height=\"36\"><\/rect>\n\t\t\t\t<\/g>\n\t\t\t<\/g>\n\t\t<\/g>\n\t<\/svg>","showScore":true,"siteFavIcon":"https:\/\/dekohra.eu\/wp-content\/uploads\/2024\/10\/cropped-NEWLOGO-50x50.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"isPro":true,"is_front_page":false,"trendsUpgradeLink":"https:\/\/dekohra.eu\/wp-admin\/admin.php?page=rank-math&view=help","trendsUpgradeLabel":"Jetzt aktivieren","trendsPreviewImage":"https:\/\/dekohra.eu\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["abgelenkt","abgesturzt","absolut","abstossend","aburd","abweisen","adaquat","aggressiv","ahnungslos","akkurat","alarmierend","alarmiert","albtraum","all-inclusive","allererste","allererster","allererstes","alleswisser","am schlechtesten","am wichtigsten","angewidert","angriff","angsteinflossend","angstlich","animiert","ankundigung","anonym","anpassbar","anspruchslos","anstossig","antagonistisch","apokalypse","applaus","argumentativ","arm","armageddon","arrogant","atemberaubend","attacke","attraktiv","aufdeckend","aufgebracht","aufgedeckt","aufgeregt","aufheiternd","aufregend","aufregende","aufregenden","aufregung","aufstachelnd","aufstandisch","aufsteigend","auftreibend","augenoffnend","ausgelassen","ausgeruht","ausgespielt","ausgewahlt","ausgewuhlt","ausnutzen","aussergewohnlich","autark","authentisch","autoritat","backdoor","badass","beangstigend","bedenklich","bedingungslos","bedrohen","bedroht","beforderung","befreit","befriedigend","befriedigt","begehren","begeistern","begeistert","begeisterung","beherzt","behind the scenes","beichte","beleidigung","belohnung","bemerkenswert","beneiden","bequem","beruhmt","beschadigen","beschamend","beschmutzt","beschuldigen","beschutzen","besitz","bessesen","bestatigen","bestatigt","beste","bestimmt","bestrafen","betrug","betrugen","bewahrt","bewiesen","bewiesenermassen","bewusst","bezahlbar","bezaubernd","bizarre","bleich","blendend","blut","blutbad","blutig","bombe","bonanza","bonus","bosartig","bose","boshaft","brilliant","brodelnd","brutal","budget","bullshit","bully","bunt","bunte","bunten","case study","cash","challenge","challgene","chaos","cheat-sheet","clever","content","cool","courage","dankbar","daruber redet keiner","deadline","definitiv","dekadent","demoralisierend","demut","desillusioniert","detailiert","diagnose","die wahrheit","direkt","disastros","discount","dokument","dollar","dominieren","doppelt","download","dreckig","dreifach","dreistigkeit","dringend","dringlichkeit","dumm","dummkopf","dummlich","durchbruch","duselig","dynamik","echt","effektiv","effizient","ehrlich","eier","eifersuchtig","eifrig","eindeutig","eindrucksvoll","eine stufe besser","einfach","einfachheit","einfallsreich","eingebildet","eingeschrankt","eingesperrt","einmalig","einsam","eintauchen","einzigartig","eisern","eliminieren","elite","empathie","empfehle","empfehlen","endeffekt","energie","energisch","enorm","entdecken","entfesselt","entfremdet","enthullen","enthullung","enthusiastisch","entmachtet","entsetzlich","entspannt","entzuckend","entzunden","epidemisch","episch","erbarmlich","erfolg","erfolgreich","erfolgsbilanz","erfreut","erfullen","erfullt","ergebnisse","ergreifen","erhaben","erheben","erhohen","erledigt","ermachtigt","ermudet","ernmutigt","ernsthaft","erobern","erroten","errungenschaft","erschaffen","erschrocken","ersehnen","ersparnisse","erstattbar","erstatten","erstaunlich","erste","ertrinken","essentiell","ethisch","euphorisch","exakt","exklusiv","exklusivitat","exkuisit","experte","explodieren","explosiv","exposed","extrem","exzellent","fahig","fahigkeiten","fail","falle","fantasie","fantastischen","farbenfroh","farbenfrohe","faszinierend","faszinierende","faul","faux pas","faux","fehler","feindselig","feldstudie","fesselnd","festlich","festmahl","festplatte","final","flirt","fluchtling","flussig","fokus","fokussiert","folter","formel","frech","freebie","frei","freiheit","freudig","friedlich","frohlich","frohlichkeit","frustriert","fundamental","fur immer","furchtbar","furchtlos","gangster","garantiert","geblendet","geehrt","gefahr","gefahrlich","gefangen","gefangnis","gefeuert","gegensatzlich","gehassig","geheimnis","geheimnisse","geil","geisseln","geist","geistesgestort","gelassen","geld zuruck","geld","genial","gepackt","gerade angekommen","gerissen","geschenk","geschmuggelt","geschutzt","gestandnis","gestandnisse","gestopft","gestresst","gesucht","gesund","getauscht","getestet","getotet","gewaltig","gewalttatig","gewidmet","gewinnspiel","gier","gierig","gift","giftig","gigantisch","giveaway","glamourose","glanzend","glaube","glaubwurdig","gleichmassig","glittering","glitzernde","gluckselig","golden","grandios","grandiose","grandiosen","grandioses","grauenhaft","grausamkeit","grinsen","groesste","gross","grossartig","grossartig","grossartige","grossartigen","grossartiger","grossartiges","grosse","grossen","grosste","grosszugig","grotesk","grube","grundlegend","gruselig","gunstig","hack","hamisch","hammer","handelsgeheimnis","hartnackig","hass","heilig","heimlich","heisshunger","heisshungrig","heiter","held","hell","herablassend","herausfordernd","herausforderung","herausvorderung","herrlichen","herrschend","hervorragend","herz","herzbrechend","herzerwahrmend","heute","hightech","hilflosigkeit","hilfreich","hilfsbereit","himmlisch","hinterhaltig","hoax","hocheffektiv","hochnasig","hochste","hoffnung","hoffnungsvoll","holle","holocaust","horror","how to","humor","hungrige","hurrikan","hypnotisch","hypnotisierend","idiot","idiotisch","illegal","immer","informativ","inhalt","inkompetent","innovativ","insider","inspirierend","inspiriert","intelligent","intensiv","interessant","interessante","invasion","investment","ist da","jackpot","jederzeit kundigen","jetzt","jubilant","jumpstart","jung","kadaver","kampf","katapult","katastrophe","kaufen","kein risiko","keine verpflichtung","kickstart","kindisch","kitschig","klaglich","klar","knast","kollabieren","kollosal","komfortabel","komisch","kompetitiv","komplett","kompromiss","komsich","konstruktiv","kontrollierend","kontrollverlust","kooperativ","kopie","korrupt","kostenlos","kraftlos","kraftvoll","krankhaft","kreativ","kreative","kriese","kritisch","kruppel","lachen","lacherlich","lahm","last minute","lauernd","lebendig","lebenslanglich","lecken","lecker","legendar","legitim","leiche","leicht","leiden","leider","leise","letzte chance","letzte","leuchtend","liberal","licht","liebe","liebenswurdig","liebevoll","life-changing","limitiert","lohnend","loser","losung","lugen","lugend","lukrativ","lust","lustig","lustige","lustigsten","luxorios","magisch","mainstream","mammut","manipulativ","massiv","masterclass","meditierend","meiseter","meistverkauft","meltdown","millionen","mind-blowing","minderwertig","minimalist","missbrauch","misstrauisch","mittelmassig","mittig","modern","moderne","moglichkeiten","monetarisieren","monumental","mord","motiviert","muhelos","muhevoll","mull","mut","mutig","nachmachen","nachteile","nackt","nagel","naiv","natural","nazi","neid","nervos","neu","niedertrachtig","niemals","notfall","notiert","nutzlich","nutzlos","offensichtlich","offiziel","offnen","ohne hintergedanken","ok","okay","okonomisch","on-demand","opfer","optimistisch","overnight","packend","panik","panzer","paralisiert","pas","passioniert","pause","payback","peinlich","perfekt","perplex","perskeptive","pessimistisch","pfund","piranha","pleite","plotzlich","pochend","polarisierend","popular","portfolio","praktisch","preis","prestige","privat","privatsphare","priviligiert","problem","produktiv","professionell","profit","profitabel","provokativ","provozierend","prozess","psychologisch","qual","qualen","qualitat","rabatt","rache","rachsuchtig","raffiniert","rasend","rat","rau","recherche","reduziert","reflektieren","regeln","reich","reiche","reichtum","relaxed","report","responsive","revolutionar","riesig","risiko","riskant","riskieren","rotzfrech","rowdy","ruckrat","ruckschlag","rucksichtlos","ruhig","ruiniert","sabotiert","sadistisch","sale","sarkastisch","scam","schabig","schadigend","schadlich","schamlos","schatz","schicksal","schlachten","schlafen","schlag","schlau","schlimm","schmerzhaft","schmerzlos","schmuggel","schnell","schnellstart","schokierend","schonheit","schrecklich","schreien","schritt fur schritt","schuld","schuldlos","schwach","schwarm","schwarzmarkt","schwerkraft","schwinden","sechsstellig","sehenswerte","selbsthass","selten","sensationell","sex","sexy","sicher","sicherheit","sicherlich","sieg","sill","simpel","sinnlich","sinnlos","skandal","skandalos","skill","sklave","sneak-peek","snob","sofort gespart","sofort","sollte","sonnig","sonnige","sonnigen","sorgen","sorgfaltig","sorglos","spannend","sparen","sparsam","spass","spassig","spektakular","speziell","spielen","spoiler","spontan","spotlight","stabil","stark","start","stoisch","stolz","stop","strahlend","strangulieren","strategie","studien","stumperhaft","stur","sunden","sundigend","super","superb","survival","tapfer","tauschend","teaser","technologie","terror","terrorist","teuer","tief","tiefgreifend","tierisch","tod","todlich","toll","tolle","toller","tortur","tot","tote","toten","totend","toxisch","tragisch","tragodie","transfomieren","transparenz","trauma","traumatisiert","traurigkeit","trend","tricks","trigger","triumpf","trocken","trotz","trugerisch","tweaks","tyrann","ubel","uberfordert","uberkommen","uberleben","uberlegen","uberraschend","uberrascht","uberraschung","uberwaltigend","uberwinden","ultimativ","umfassend","umstritten","umwerfend","unatorisiert","unaufhaltbar","unausgelasted","unbedacht","unbeliebt","unbeschwert","unbewusst","undercover","undokumentiert","unehrlich","unentschlossen","unerwartet","unfahig","ungeduldig","ungedult","ungehort","ungemutlich","ungerechtfertigt","ungesehen","ungetrubt","ungewohnlich","ungezogen","unglaublich","unglaubliches","uninteressiert","unkontrollierbar","unkonventionell","unlimitiert","unpenetrierbar","unschuldig","unsicher","unstabil","unter verschluss","untergrund","unterhaltsam","unterstutz","unterstutzend","unubertroffen","unvergesslich","unverneinbar","unvoreingenommen","unwiderstehlich","unwirtlich","unzensiert","unzuverlassig","up-selling","vaporisieren","verangstigt","verantwortlich","verargert","verarscht","verbessert","verbluffend","verblufft","verboten","verbreiten","verdachtig","verdammt","verdeckt","vereinfacht","verfuhrend","vergebend","vergessen","vergleich","verhauen","verifizieren","verkommen","verlegen","verletzbar","verletzt","verlockend","verloren","vermasselt","vermeiden","vermogen","vernichten","vernichtend","vernunftig","veroffentlichung","verpassen","verraterisch","verruckt","versagen","verschwitzt","versichert","verspielt","versprechend","versteckt","vertrauenswurdig","vertraulich","vertraumt","verurteilend","verwunderlich","verwundet","verzaubernd","verzweifelt","vierfach","vogelfrei","vollig","vollstandig","vorsicht","vorstellungskraft","vorteil","wachstum","wagemutig","wahnsinn","wahnsinnig","wahrhaftig","wahrheit","wahrheitsgemass","wahrscheinlich","warnung","was dir keiner sagt","wehleidig","welt","wenig bekannt","wert","wertvoll","wichtig","widerlich","wiedererkannt","wild","wilde","wilden","willensstarke","wirr","wohltatigkeit","wortlich","wunder","wunderbar","wunderbaren","wunderschon","wutend","zeichen","zeitig","zen","zensiert","zerschlagen","zerschmetternd","zerstorend","zertifiziert","zielorientiert","zischend","zischt","zocken","zogernd","zugeben","zuruckgehalten","zuruckgelassen","zuruckweisen","zusatzlich","zutaten","zuverlassig","zwangsernahrt","zweifelnd","zwickend","zwingend","einfache","einfachen","einfaches","einfacher","simple","simplen","simples","simpler","besten","bestes","bester","beste","bestbewertet","bestbewerteten","bestbewertete","bestbewerteter","bestbewertetes","\u00fcberraschende","\u00fcberraschenden","\u00fcberraschendes","\u00fcberraschender","hilfreiche","hilfreiches","hilfreichen","hilfreicher","f\u00f6rdern","unterst\u00fctzen","helfen","spielerisch","spannende","spannendes","spannenden","spannender","gro\u00dfartige","gro\u00dfartiges","gro\u00dfartigen","gro\u00dfartiger","ideal","ideales","idealen","idealer","faszinierend","faszinierendes","faszinierenden","faszinierender","wichtig","wichtige","wichtiges","wichtigen","wichtiger","sicher","sichere","sicheres","sicheren","sicherer","umfassende","umfassendes","umfassenden","umfassender","ultimative","ultimatives","ultimativen","ultimativer","einzigartige","einzigartiges","einzigartigen","einzigartiger"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"isAnalyticsConnected":true,"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/dekohra.eu\/de\/wp-json\/wp\/v2\/pages\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dekohra.eu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dekohra.eu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dekohra.eu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dekohra.eu\/de\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":0,"href":"https:\/\/dekohra.eu\/de\/wp-json\/wp\/v2\/pages\/171\/revisions"}],"wp:attachment":[{"href":"https:\/\/dekohra.eu\/de\/wp-json\/wp\/v2\/media?parent=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}